{"id":202,"date":"2024-10-27T00:29:00","date_gmt":"2024-10-26T22:29:00","guid":{"rendered":"https:\/\/ilmillenniox12.com\/edicola\/?p=202"},"modified":"2025-01-04T00:38:54","modified_gmt":"2025-01-03T23:38:54","slug":"il-millennio-x12-del-27-10-2024","status":"publish","type":"post","link":"https:\/\/ilmillenniox12.com\/edicola\/2024\/10\/27\/il-millennio-x12-del-27-10-2024\/","title":{"rendered":"Il Millennio X12 del 27\/10\/2024"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"882\" height=\"1024\" src=\"https:\/\/ilmillenniox12.com\/edicola\/wp-content\/uploads\/sites\/6\/2025\/01\/MILLE35-882x1024.png\" alt=\"\" class=\"wp-image-203\" srcset=\"https:\/\/ilmillenniox12.com\/edicola\/wp-content\/uploads\/sites\/6\/2025\/01\/MILLE35-882x1024.png 882w, https:\/\/ilmillenniox12.com\/edicola\/wp-content\/uploads\/sites\/6\/2025\/01\/MILLE35-258x300.png 258w, https:\/\/ilmillenniox12.com\/edicola\/wp-content\/uploads\/sites\/6\/2025\/01\/MILLE35-768x892.png 768w, https:\/\/ilmillenniox12.com\/edicola\/wp-content\/uploads\/sites\/6\/2025\/01\/MILLE35-936x1087.png 936w, https:\/\/ilmillenniox12.com\/edicola\/wp-content\/uploads\/sites\/6\/2025\/01\/MILLE35.png 1280w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":203,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-il-millennio-x12","wpcat-3-id"],"jetpack_featured_media_url":"https:\/\/ilmillenniox12.com\/edicola\/wp-content\/uploads\/sites\/6\/2025\/01\/MILLE35.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ilmillenniox12.com\/edicola\/wp-json\/wp\/v2\/posts\/202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ilmillenniox12.com\/edicola\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ilmillenniox12.com\/edicola\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ilmillenniox12.com\/edicola\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ilmillenniox12.com\/edicola\/wp-json\/wp\/v2\/comments?post=202"}],"version-history":[{"count":1,"href":"https:\/\/ilmillenniox12.com\/edicola\/wp-json\/wp\/v2\/posts\/202\/revisions"}],"predecessor-version":[{"id":204,"href":"https:\/\/ilmillenniox12.com\/edicola\/wp-json\/wp\/v2\/posts\/202\/revisions\/204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ilmillenniox12.com\/edicola\/wp-json\/wp\/v2\/media\/203"}],"wp:attachment":[{"href":"https:\/\/ilmillenniox12.com\/edicola\/wp-json\/wp\/v2\/media?parent=202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ilmillenniox12.com\/edicola\/wp-json\/wp\/v2\/categories?post=202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ilmillenniox12.com\/edicola\/wp-json\/wp\/v2\/tags?post=202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}